{"id":18121,"date":"2023-01-04T12:41:24","date_gmt":"2023-01-04T11:41:24","guid":{"rendered":"https:\/\/hosteleo.com\/blog\/?p=18121"},"modified":"2023-01-04T12:41:26","modified_gmt":"2023-01-04T11:41:26","slug":"la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla","status":"publish","type":"post","link":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/","title":{"rendered":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla"},"content":{"rendered":"\n<p>La ayuda de 100 euros por hijo\/a a cargo, tambi\u00e9n conocida como complemento de ayuda a la infancia, es una prestaci\u00f3n que nace con el principal objetivo de <strong>ayudar a familias con rentas bajas y ni\u00f1os\/as menores a cargo<\/strong>. Actualmente, y a pesar de haber vivido un notable descenso en las cifras registradas en el mes de diciembre, el paro contin\u00faa siendo muy elevado en nuestro pa\u00eds, y son muchos los trabajadores de <a href=\"https:\/\/linkers.es\/\">personal de hosteler\u00eda<\/a> que siguen sin encontrar un hueco en el mercado laboral. En esta ocasi\u00f3n, <strong>la ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023<\/strong>, y a continuaci\u00f3n te contaremos cu\u00e1les son los nuevos requisitos para poder solicitarla.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQui\u00e9n puedes solicitar la ayuda de 100 euros por hijo\/a a cargo?<\/h2>\n\n\n\n<p>En un primer momento, este complemento fue creado para ayudar a los beneficiarios del Ingreso M\u00ednimo Vital, que tuvieran hijos\/as a menores a su cargo. Actualmente, esta ayuda se ha generalizado, y <strong>podr\u00e1n beneficiarse de esta prestaci\u00f3n todas aquellas personas que se encuentren en alguna de las siguientes situaciones<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Mujeres con hijos\/as menores de 3 a\u00f1os.<\/li><li>El padre o tutor en caso de fallecimiento de la madre.<\/li><li>El padre o tutor cuando la guarda y custodia completa.<\/li><li>En el caso de que ambos progenitores sean del mismo sexo, los dos tendr\u00e1n derecho a la ayuda.<\/li><li>Cuando los padres tengan derecho a la aplicaci\u00f3n del m\u00ednimo por descendientes por estos menores.<\/li><li>Cuando realicen una actividad por cuenta propia o ajena, y est\u00e9n dados de alta en el r\u00e9gimen correspondiente de la Seguridad Social o Mutualidad.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Nuevos requisitos para solicitarla<\/h2>\n\n\n\n<p>Tras la reciente modificaci\u00f3n de la Ley de Familias por parte del Gobierno, los requisitos para optar a este complemento tambi\u00e9n han sufrido variaciones, y podr\u00e1n solicitarlo aquellas <strong>personas que tengan hijos\/as de entre 0 y 3 a\u00f1os y que hayan cotizado un m\u00ednimo de 30 d\u00edas a la Seguridad Social o que hayan recibido una prestaci\u00f3n contributiva o asistencial<\/strong> del sistema de prestaci\u00f3n por desempleo.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo solicitar la ayuda de 100 euros por hijo\/a<\/h2>\n\n\n\n<p>Este complemento est\u00e1 tramitado y expedido por la Agencia Tributaria, por lo que para solicitarlo, <strong>habr\u00e1 que presentar el Modelo 140 de solicitud<\/strong>. Puedes descargarlo <a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/procedimientoini\/GZ25.shtml\">pinchando aqu\u00ed<\/a>. A continuaci\u00f3n, tendremos que <strong>completarlo con nuestros datos personales y profesionales<\/strong>, y dispondremos de 3 v\u00edas diferentes para presentarlo:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>En primer lugar, <strong>por Internet, a trav\u00e9s de la Sede Electr\u00f3nica de la Agencia Tributaria<\/strong>. Puedes ir directamente <a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/procedimientoini\/GZ25.shtml\">pinchando aqu\u00ed<\/a>. Es necesario recordar que para hacerlo v\u00eda telem\u00e1tica ser\u00e1 necesario disponer de DNI electr\u00f3nico, certificado digital o usuario Cl@ve.<\/li><li><strong>Presencialmente acudiendo a una Delegaci\u00f3n o Administraci\u00f3n de la Agencia Tributaria<\/strong>. Para ello, ser\u00e1 necesario solicitar siempre cita con antelaci\u00f3n. Adem\u00e1s, en el caso de hacerlo de forma presencial, habr\u00e1 que descargar, imprimir y completar el modelo 140 para poder presentarlo posteriormente en la oficina.<\/li><li>Por \u00faltimo, <strong>tambi\u00e9n se podr\u00e1 solicitar v\u00eda telef\u00f3nica<\/strong> mediante el n\u00famero gratuito del Centro de Atenci\u00f3n Telef\u00f3nica de la Agencia Tributaria. Este es: <strong>901 200 347<\/strong>.<\/li><\/ol>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e1s informaci\u00f3n sobre ayudas y prestaciones:<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/hosteleo.com\/blog\/estas-son-las-cuantias-de-paro-para-el-2023-tras-la-nueva-subida\/\">Estas son las cuant\u00edas de paro para el 2023 tras la nueva subida.<\/a><\/li><li><a href=\"https:\/\/hosteleo.com\/blog\/autonomos-la-seguridad-social-lanza-un-simulador-para-poder-calcular-la-cuota-que-pagaran-en-2023\/\">Aut\u00f3nomos: la Seguridad Social lanza un simulador para poder calcular la cuota que pagar\u00e1n en 2023.<\/a><\/li><li><a href=\"https:\/\/hosteleo.com\/blog\/claves-de-la-nueva-ley-de-empleo-para-2023\/\">Claves de la nueva Ley de Empleo para 2023.<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La ayuda de 100 euros por hijo\/a a cargo, tambi\u00e9n conocida como complemento de ayuda a la infancia, es una prestaci\u00f3n que nace con el principal objetivo de ayudar a familias con rentas bajas y ni\u00f1os\/as menores a cargo. Actualmente, y a pesar de haber vivido un notable descenso en las cifras registradas en el [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":11991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[944],"tags":[1933,2116,2134,984,677,2267,2119,2137,2128,4263,4738,515,1015,2778],"class_list":["post-18121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ayudas-y-prestaciones","tag-agencia-tributaria","tag-ayuda-a-la-infancia","tag-ayuda-de-100-euros","tag-ayudas","tag-ayudas-hosteleria","tag-ayudas-publicas","tag-complemento-ayuda-a-la-infancia","tag-complemento-de-100-euros","tag-complemento-menor-a-cargo","tag-hijo-a-cargo","tag-ingreso-minimo-vital-2","tag-prestaciones","tag-requisitos","tag-responsabilidades-familiares"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo<\/title>\n<meta name=\"description\" content=\"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla y c\u00f3mo hacerlo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\" \/>\n<meta property=\"og:description\" content=\"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla y c\u00f3mo hacerlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hosteleo\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T11:41:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-04T11:41:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2022\/04\/Logo_de_la_Agencia_Tributaria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"496\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucia Mendez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hosteleo\" \/>\n<meta name=\"twitter:site\" content=\"@hosteleo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucia Mendez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/\"},\"author\":{\"name\":\"Lucia Mendez\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/person\\\/79ebcc3f4d55b944b967a365a656f908\"},\"headline\":\"La ayuda de 100 euros por hijo\\\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla\",\"datePublished\":\"2023-01-04T11:41:24+00:00\",\"dateModified\":\"2023-01-04T11:41:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/\"},\"wordCount\":596,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_de_la_Agencia_Tributaria.jpg\",\"keywords\":[\"Agencia tributaria\",\"ayuda a la infancia\",\"ayuda de 100 euros\",\"ayudas\",\"ayudas hosteleria\",\"Ayudas p\u00fablicas\",\"complemento ayuda a la infancia\",\"complemento de 100 euros\",\"complemento menor a cargo\",\"hijo a cargo\",\"ingreso m\u00ednimo vital\",\"prestaciones\",\"requisitos\",\"Responsabilidades familiares\"],\"articleSection\":[\"Ayudas y prestaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/\",\"name\":\"La ayuda de 100 euros por hijo\\\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_de_la_Agencia_Tributaria.jpg\",\"datePublished\":\"2023-01-04T11:41:24+00:00\",\"dateModified\":\"2023-01-04T11:41:26+00:00\",\"description\":\"La ayuda de 100 euros por hijo\\\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla y c\u00f3mo hacerlo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_de_la_Agencia_Tributaria.jpg\",\"contentUrl\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_de_la_Agencia_Tributaria.jpg\",\"width\":496,\"height\":330,\"caption\":\"Aviso del SEPE sobre c\u00f3mo descargar el certificado del IRPF para hacer la Declaraci\u00f3n de la Renta 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ayuda de 100 euros por hijo\\\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/\",\"name\":\"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\",\"description\":\"Tu blog de Empleo en Hosteler\u00eda y Turismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#organization\",\"name\":\"Hosteleo\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hosteleo.wizzie.dev\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-hosteleo.png\",\"contentUrl\":\"https:\\\/\\\/hosteleo.wizzie.dev\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-hosteleo.png\",\"width\":475,\"height\":76,\"caption\":\"Hosteleo\"},\"image\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hosteleo\",\"https:\\\/\\\/x.com\\\/hosteleo\",\"https:\\\/\\\/www.instagram.com\\\/hosteleo\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/hosteleo-com\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/person\\\/79ebcc3f4d55b944b967a365a656f908\",\"name\":\"Lucia Mendez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g\",\"caption\":\"Lucia Mendez\"},\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/author\\\/lucia-mendez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","description":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla y c\u00f3mo hacerlo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/","og_locale":"es_ES","og_type":"article","og_title":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","og_description":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla y c\u00f3mo hacerlo.","og_url":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/","og_site_name":"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","article_publisher":"https:\/\/www.facebook.com\/hosteleo","article_published_time":"2023-01-04T11:41:24+00:00","article_modified_time":"2023-01-04T11:41:26+00:00","og_image":[{"width":496,"height":330,"url":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2022\/04\/Logo_de_la_Agencia_Tributaria.jpg","type":"image\/jpeg"}],"author":"Lucia Mendez","twitter_card":"summary_large_image","twitter_creator":"@hosteleo","twitter_site":"@hosteleo","twitter_misc":{"Escrito por":"Lucia Mendez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#article","isPartOf":{"@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/"},"author":{"name":"Lucia Mendez","@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/person\/79ebcc3f4d55b944b967a365a656f908"},"headline":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla","datePublished":"2023-01-04T11:41:24+00:00","dateModified":"2023-01-04T11:41:26+00:00","mainEntityOfPage":{"@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/"},"wordCount":596,"commentCount":2,"publisher":{"@id":"https:\/\/hosteleo.com\/blog\/#organization"},"image":{"@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#primaryimage"},"thumbnailUrl":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2022\/04\/Logo_de_la_Agencia_Tributaria.jpg","keywords":["Agencia tributaria","ayuda a la infancia","ayuda de 100 euros","ayudas","ayudas hosteleria","Ayudas p\u00fablicas","complemento ayuda a la infancia","complemento de 100 euros","complemento menor a cargo","hijo a cargo","ingreso m\u00ednimo vital","prestaciones","requisitos","Responsabilidades familiares"],"articleSection":["Ayudas y prestaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/","url":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/","name":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","isPartOf":{"@id":"https:\/\/hosteleo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#primaryimage"},"image":{"@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#primaryimage"},"thumbnailUrl":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2022\/04\/Logo_de_la_Agencia_Tributaria.jpg","datePublished":"2023-01-04T11:41:24+00:00","dateModified":"2023-01-04T11:41:26+00:00","description":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla y c\u00f3mo hacerlo.","breadcrumb":{"@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#primaryimage","url":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2022\/04\/Logo_de_la_Agencia_Tributaria.jpg","contentUrl":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2022\/04\/Logo_de_la_Agencia_Tributaria.jpg","width":496,"height":330,"caption":"Aviso del SEPE sobre c\u00f3mo descargar el certificado del IRPF para hacer la Declaraci\u00f3n de la Renta 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/hosteleo.com\/blog\/la-ayuda-de-100-euros-por-hijo-a-a-cargo-se-mantendra-durante-2023-requisitos-para-solicitarla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hosteleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La ayuda de 100 euros por hijo\/a a cargo se mantendr\u00e1 durante 2023: requisitos para solicitarla"}]},{"@type":"WebSite","@id":"https:\/\/hosteleo.com\/blog\/#website","url":"https:\/\/hosteleo.com\/blog\/","name":"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","description":"Tu blog de Empleo en Hosteler\u00eda y Turismo","publisher":{"@id":"https:\/\/hosteleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hosteleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hosteleo.com\/blog\/#organization","name":"Hosteleo","url":"https:\/\/hosteleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hosteleo.wizzie.dev\/blog\/wp-content\/uploads\/2020\/05\/logo-hosteleo.png","contentUrl":"https:\/\/hosteleo.wizzie.dev\/blog\/wp-content\/uploads\/2020\/05\/logo-hosteleo.png","width":475,"height":76,"caption":"Hosteleo"},"image":{"@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hosteleo","https:\/\/x.com\/hosteleo","https:\/\/www.instagram.com\/hosteleo\/","https:\/\/es.linkedin.com\/company\/hosteleo-com"]},{"@type":"Person","@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/person\/79ebcc3f4d55b944b967a365a656f908","name":"Lucia Mendez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g","caption":"Lucia Mendez"},"url":"https:\/\/hosteleo.com\/blog\/author\/lucia-mendez\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts\/18121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/comments?post=18121"}],"version-history":[{"count":1,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts\/18121\/revisions"}],"predecessor-version":[{"id":18127,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts\/18121\/revisions\/18127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/media\/11991"}],"wp:attachment":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/media?parent=18121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/categories?post=18121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/tags?post=18121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}