{"id":7952,"date":"2021-10-23T10:31:35","date_gmt":"2021-10-23T10:31:35","guid":{"rendered":"https:\/\/hosteleo.com\/blog\/?p=7952"},"modified":"2021-10-23T10:31:37","modified_gmt":"2021-10-23T10:31:37","slug":"madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria","status":"publish","type":"post","link":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/","title":{"rendered":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda"},"content":{"rendered":"\n<p>Con la gran demanda de puestos de trabajo ofertados en el sector de la hosteler\u00eda, cada vez son m\u00e1s empresas las que buscan personal formado y con experiencia para incorporarse a sus plantillas. Para ello, el <strong>Ayuntamiento de Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda.<\/strong><\/p>\n\n\n\n<p>Con este curso, se pretende ense\u00f1ar nuevos contenidos pr\u00e1cticos y experiencia principalmente a trav\u00e9s de situaciones con las que se encontrar\u00e1 el trabajador. <strong>Tendr\u00e1 comienzo el d\u00eda 25 de octubre y una duraci\u00f3n de 75 horas repartidas en 3 semanas en clases tanto online como presenciales.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 se imparte en el curso<\/h2>\n\n\n\n<p>Este curso se divide en <strong>tres fases principales<\/strong> a la hora de impartir sus temarios:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Una fase de calentamiento.  <\/strong>En esta primera fase se entrega todo el material necesario para la realizaci\u00f3n del curso, te preparan y acercan a trav\u00e9s de videos hacia las nuevas habilidades que se impartir\u00e1n posteriormente. Tambi\u00e9n realizar\u00e1s dos actividades de autoevaluaci\u00f3n. <\/li><li><strong>Fase de entrenamiento. <\/strong>Tiene una duraci\u00f3n de una semana y en ella habr\u00e1 tanto clases  presenciales como 4 horas de clases virtuales. En esta fase se pretende dar el contenido completo de las materias, habilidades blandas o sociales, innovaci\u00f3n y herramientas digitales.<\/li><li><strong>Fase de alto rendimiento.<\/strong> En esta \u00faltima fase se busca \u00fanicamente la puesta en pr\u00e1ctica de las habilidades y contenidos aprendidos durante el curso. Te dar\u00e1n una serie de pautas e indicaciones para aplicarlos en un contexto de trabajo.<\/li><\/ul>\n\n\n\n<p>Durante estas tres fases tambi\u00e9n <strong>se incluyen las habilidades y herramientas en las necesidades m\u00e1s estrat\u00e9gicas del sector, la transformaci\u00f3n digital o trabajo en retos reales entre otros.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo apuntarse<\/h2>\n\n\n\n<p>Para <strong>apuntarse en el nuevo curso gratuito con 40 plazas que lanza el Ayuntamiento de Madrid para formarte en el sector de la hosteler\u00eda, <\/strong>lo primero que debes hacer es <strong>acceder a la p\u00e1gina web del Ayuntamiento de Madrid, <\/strong>puedes hacerlo directamente <a href=\"https:\/\/www.madrid.es\/portal\/site\/munimadrid\">pinchando aqu\u00ed.<\/a> Tras esto, deber\u00e1s <strong>pinchar en la lupa situada en la parte de arriba a la derecha y se te abrir\u00e1 la barra de b\u00fasquedas.<\/strong> En ella tendr\u00e1s que <strong>poner &#8220;Gastro emplea&#8221;. <\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"463\" src=\"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-1024x463.jpg\" alt=\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda\" class=\"wp-image-7958\" srcset=\"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-1024x463.jpg 1024w, https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-300x136.jpg 300w, https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-768x347.jpg 768w, https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-1536x694.jpg 1536w, https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-810x366.jpg 810w, https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2-1140x515.jpg 1140w, https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/Screenshot_20211023-122013_Chrome2.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Una vez dentro, debes <strong>pinchar en el apartado<a href=\"https:\/\/www.madrid.es\/portales\/munimadrid\/es\/FormularioElectronico\/Inicio\/Buscador\/Formulario-de-solicitud-Gastro-Emplea\/?vgnextfmt=default&amp;vgnextoid=6cba85ab88b3c710VgnVCM1000001d4a900aRCRD&amp;vgnextchannel=7db8fc12aa936610VgnVCM1000008a4a900aRCRD\"> &#8220;Formulario de solicitud &#8211;  Gastro emplea&#8221;.<\/a> <\/strong>Finalmente, tienes que <strong>rellenar el formulario y enviarlo.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tambi\u00e9n puede interesarte: <\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/hosteleo.com\/blog\/nuevas-vacantes-para-trabajar-como-camarero-en-las-salas-vip-del-aeropuerto-de-madrid\/\">Nuevas vacantes para trabajar como camarero en las salas VIP del aeropuerto de Madrid<\/a><\/li><li><a href=\"https:\/\/hosteleo.com\/blog\/el-chef-con-tres-estrellas-michelin-quique-dacosta-busca-cocineros-para-sus-restaurantes\/\">El chef con tres Estrellas Michel\u00edn Quique Dacosta busca cocineros para sus restaurantes<\/a><\/li><li><a href=\"https:\/\/hosteleo.com\/blog\/el-reconocido-restaurante-asiatico-china-crown-busca-personal\/\">El reconocido restaurante asi\u00e1tico China Crown busca personal<\/a><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Con la gran demanda de puestos de trabajo ofertados en el sector de la hosteler\u00eda, cada vez son m\u00e1s empresas las que buscan personal formado y con experiencia para incorporarse a sus plantillas. Para ello, el Ayuntamiento de Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":7964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[41],"tags":[670,1235,1238,1250,1244,1241,1256,1259,130,1247,82,1253],"class_list":["post-7952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-empleo-hosteleria-turismo","tag-ayuntamiento-de-madrid","tag-curso","tag-curso-gratuito","tag-curso-gratuito-madrid","tag-curso-hosteleria","tag-curso-madrid","tag-formacion-2","tag-formacion-en-hosteleria-2","tag-hosteleria-2","tag-hosteleria-madrid","tag-madrid","tag-nuevo-curso"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo<\/title>\n<meta name=\"description\" content=\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. Tendr\u00e1 comienzo el 25 de octubre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\" \/>\n<meta property=\"og:description\" content=\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. Tendr\u00e1 comienzo el 25 de octubre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hosteleo\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-23T10:31:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-23T10:31:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lucia Mendez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hosteleo\" \/>\n<meta name=\"twitter:site\" content=\"@hosteleo\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lucia Mendez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/\"},\"author\":{\"name\":\"Lucia Mendez\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/person\\\/79ebcc3f4d55b944b967a365a656f908\"},\"headline\":\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda\",\"datePublished\":\"2021-10-23T10:31:35+00:00\",\"dateModified\":\"2021-10-23T10:31:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/\"},\"wordCount\":451,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg\",\"keywords\":[\"Ayuntamiento de Madrid\",\"Curso\",\"Curso gratuito\",\"Curso gratuito Madrid\",\"Curso hosteleria\",\"Curso Madrid\",\"formaci\u00f3n\",\"formaci\u00f3n en hosteler\u00eda\",\"hosteleria\",\"Hosteleria Madrid\",\"madrid\",\"Nuevo curso\"],\"articleSection\":[\"Noticias de Empleo en Hosteler\u00eda y Turismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/\",\"name\":\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg\",\"datePublished\":\"2021-10-23T10:31:35+00:00\",\"dateModified\":\"2021-10-23T10:31:37+00:00\",\"description\":\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. Tendr\u00e1 comienzo el 25 de octubre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg\",\"contentUrl\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/\",\"name\":\"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo\",\"description\":\"Tu blog de Empleo en Hosteler\u00eda y Turismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#organization\",\"name\":\"Hosteleo\",\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hosteleo.wizzie.dev\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-hosteleo.png\",\"contentUrl\":\"https:\\\/\\\/hosteleo.wizzie.dev\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/logo-hosteleo.png\",\"width\":475,\"height\":76,\"caption\":\"Hosteleo\"},\"image\":{\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/hosteleo\",\"https:\\\/\\\/x.com\\\/hosteleo\",\"https:\\\/\\\/www.instagram.com\\\/hosteleo\\\/\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/hosteleo-com\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/#\\\/schema\\\/person\\\/79ebcc3f4d55b944b967a365a656f908\",\"name\":\"Lucia Mendez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g\",\"caption\":\"Lucia Mendez\"},\"url\":\"https:\\\/\\\/hosteleo.com\\\/blog\\\/author\\\/lucia-mendez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","description":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. Tendr\u00e1 comienzo el 25 de octubre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/","og_locale":"es_ES","og_type":"article","og_title":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","og_description":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. Tendr\u00e1 comienzo el 25 de octubre.","og_url":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/","og_site_name":"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","article_publisher":"https:\/\/www.facebook.com\/hosteleo","article_published_time":"2021-10-23T10:31:35+00:00","article_modified_time":"2021-10-23T10:31:37+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg","type":"image\/jpeg"}],"author":"Lucia Mendez","twitter_card":"summary_large_image","twitter_creator":"@hosteleo","twitter_site":"@hosteleo","twitter_misc":{"Escrito por":"Lucia Mendez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#article","isPartOf":{"@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/"},"author":{"name":"Lucia Mendez","@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/person\/79ebcc3f4d55b944b967a365a656f908"},"headline":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda","datePublished":"2021-10-23T10:31:35+00:00","dateModified":"2021-10-23T10:31:37+00:00","mainEntityOfPage":{"@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/"},"wordCount":451,"commentCount":3,"publisher":{"@id":"https:\/\/hosteleo.com\/blog\/#organization"},"image":{"@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#primaryimage"},"thumbnailUrl":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg","keywords":["Ayuntamiento de Madrid","Curso","Curso gratuito","Curso gratuito Madrid","Curso hosteleria","Curso Madrid","formaci\u00f3n","formaci\u00f3n en hosteler\u00eda","hosteleria","Hosteleria Madrid","madrid","Nuevo curso"],"articleSection":["Noticias de Empleo en Hosteler\u00eda y Turismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/","url":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/","name":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda - Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","isPartOf":{"@id":"https:\/\/hosteleo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#primaryimage"},"image":{"@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#primaryimage"},"thumbnailUrl":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg","datePublished":"2021-10-23T10:31:35+00:00","dateModified":"2021-10-23T10:31:37+00:00","description":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda. Tendr\u00e1 comienzo el 25 de octubre.","breadcrumb":{"@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#primaryimage","url":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg","contentUrl":"https:\/\/hosteleo.com\/blog\/wp-content\/uploads\/2021\/10\/oficina-ordenador-internet-trabajo-2-1024x683-1.jpg","width":1024,"height":683,"caption":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda"},{"@type":"BreadcrumbList","@id":"https:\/\/hosteleo.com\/blog\/madrid-lanza-un-nuevo-curso-gratuito-con-40-plazas-para-formarte-en-el-sector-de-la-hosteleria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hosteleo.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Madrid lanza un nuevo curso gratuito con 40 plazas para formarte en el sector de la hosteler\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/hosteleo.com\/blog\/#website","url":"https:\/\/hosteleo.com\/blog\/","name":"Blog de Empleo en Hosteler\u00eda y Turismo - Hosteleo","description":"Tu blog de Empleo en Hosteler\u00eda y Turismo","publisher":{"@id":"https:\/\/hosteleo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hosteleo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/hosteleo.com\/blog\/#organization","name":"Hosteleo","url":"https:\/\/hosteleo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/hosteleo.wizzie.dev\/blog\/wp-content\/uploads\/2020\/05\/logo-hosteleo.png","contentUrl":"https:\/\/hosteleo.wizzie.dev\/blog\/wp-content\/uploads\/2020\/05\/logo-hosteleo.png","width":475,"height":76,"caption":"Hosteleo"},"image":{"@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hosteleo","https:\/\/x.com\/hosteleo","https:\/\/www.instagram.com\/hosteleo\/","https:\/\/es.linkedin.com\/company\/hosteleo-com"]},{"@type":"Person","@id":"https:\/\/hosteleo.com\/blog\/#\/schema\/person\/79ebcc3f4d55b944b967a365a656f908","name":"Lucia Mendez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/939287419fd9cfab10c87d595914d23a9b8797cd8fd6219748cc4e95cbd92fca?s=96&d=mm&r=g","caption":"Lucia Mendez"},"url":"https:\/\/hosteleo.com\/blog\/author\/lucia-mendez\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts\/7952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/comments?post=7952"}],"version-history":[{"count":2,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts\/7952\/revisions"}],"predecessor-version":[{"id":7967,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/posts\/7952\/revisions\/7967"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/media\/7964"}],"wp:attachment":[{"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/media?parent=7952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/categories?post=7952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hosteleo.com\/blog\/wp-json\/wp\/v2\/tags?post=7952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}